{"id":7741,"date":"2023-08-31T16:28:31","date_gmt":"2023-08-31T16:28:31","guid":{"rendered":"http:\/\/sakwinetravel.com\/?page_id=7741"},"modified":"2026-06-30T11:06:31","modified_gmt":"2026-06-30T11:06:31","slug":"climb-aconcagua","status":"publish","type":"page","link":"https:\/\/sakwinetravel.com\/pt\/pacotes-em-mendoza\/escalar-o-aconcagua\/","title":{"rendered":"Passeios no Aconc\u00e1gua"},"content":{"rendered":"<div id=\"page-header-1299857176\" class=\"page-header-wrapper\">\n  <div class=\"page-title dark featured-title\">\n\n        <div class=\"page-title-bg\">\n      <div class=\"title-bg fill bg-fill\"\n        data-parallax-container=\".page-title\"\n        data-parallax-background\n data-parallax=\"-\">\n      <\/div>\n      <div class=\"title-overlay fill\"><\/div>\n    <\/div>\n    \n    <div class=\"page-title-inner container align-center text-center flex-row-col medium-flex-wrap\" >\n              <div class=\"title-wrapper flex-col\">\n          <h1 class=\"entry-title mb-0\">\n            Escalar o Aconc\u00e1gua em Mendoza          <\/h1>\n        <\/div>\n                    <div class=\"title-content flex-col\">\n        <div class=\"title-breadcrumbs pb-half pt-half\"><nav class=\"woocommerce-breadcrumb breadcrumbs uppercase\" aria-label=\"Breadcrumb\" data-no-translation=\"\" data-trp-gettext=\"\">In\u00edcio<\/nav><\/div>      <\/div>\n    <\/div>\n\n     \n<style>\n#page-header-1299857176 .page-title-inner {\n  min-height: 250px;\n}\n#page-header-1299857176 {\n  margin-bottom: 0px;\n}\n#page-header-1299857176 .title-bg {\n  background-image: url(https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/12\/Aconcagua-5.jpeg);\n  background-position: 63% 48%;\n}\n<\/style>\n  <\/div>\n    <\/div>\n  \n\n<div class=\"row\"  id=\"row-1764608296\">\n\n\n\t<div id=\"col-1890099359\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-328003281\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-328003281 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a href=\"https:\/\/forms.zohopublic.com\/nicolas30\/form\/InquirySAKWineTravel\/formperma\/qeUBBtY3-hZ1b66jmgm83Ya3p95TgPrHPGid_mIEmvY\" class=\"button success\" rel=\"nofollow noopener\" target=\"_blank\">\n\t\t<span>SOLICITAR UMA COTA\u00c7\u00c3O<\/span>\n\t<\/a>\n\n\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Com 6.962 metros acima do n\u00edvel do mar, o Aconc\u00e1gua \u00e9 o pico mais alto das Am\u00e9ricas e um dos Sete Cumes. Todo ano, alpinistas e trilheiros de todo o mundo viajam para Mendoza pra testar seus limites nas encostas do Aconc\u00e1gua. Alguns querem chegar ao cume. Outros v\u00eam pra caminhar pelos vales, chegar ao acampamento base ou simplesmente ficar perto o suficiente pra sentir a grandiosidade da montanha.<\/span><\/p>\n\t<div id=\"gap-149260419\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-149260419 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >UM TOUR ACONCAGUA PARA O SEU ESTILO<\/span><b aria-hidden=\"true\"><\/b><\/h2><\/div>\n\n<div class=\"row\"  id=\"row-116442080\">\n\n\n\t<div id=\"col-231620000\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/sakwinetravel.com\/pt\/pacotes-em-mendoza\/escalar-o-aconcagua\/cupula\/\">\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/12\/Aconcagua-5.jpeg\" class=\"attachment- size-\" alt=\"Passeios de vinho em Mendoza e cume do aconc\u00e1gua\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/12\/Aconcagua-5.jpeg 1280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/12\/Aconcagua-5-510x383.jpeg 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/12\/Aconcagua-5-533x400.jpeg 533w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/12\/Aconcagua-5-1067x800.jpeg 1067w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/12\/Aconcagua-5-768x576.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>CUME - ROTA NORMAL<\/h3>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1700712127\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/sakwinetravel.com\/pt\/pacotes-em-mendoza\/escalar-o-aconcagua\/rota-360\/\">\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/plaza-franca-e1579722487616.jpg\" class=\"attachment- size-\" alt=\"trekking no aconc\u00e1gua\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/plaza-franca-e1579722487616.jpg 700w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/plaza-franca-e1579722487616-247x247.jpg 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/plaza-franca-e1579722487616-100x100.jpg 100w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/plaza-franca-e1579722487616-510x510.jpg 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/plaza-franca-e1579722487616-280x280.jpg 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/plaza-franca-e1579722487616-400x400.jpg 400w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>ROTA 360<\/h3>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-941490205\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/sakwinetravel.com\/pt\/pacotes-em-mendoza\/escalar-o-aconcagua\/caminhada-no-acampamento-base\/\">\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/plaza-francia2.jpg\" class=\"attachment- size-\" alt=\"trekking no aconc\u00e1gua\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/plaza-francia2.jpg 800w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/plaza-francia2-400x400.jpg 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/plaza-francia2-280x280.jpg 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/plaza-francia2-768x768.jpg 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/plaza-francia2-247x247.jpg 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/plaza-francia2-510x510.jpg 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/plaza-francia2-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>CAMINHADA NO ACAMPAMENTO BASE<\/h3>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >Expedi\u00e7\u00f5es de V\u00c1RIOS DIAS AO ACONCAGUA<\/span><b aria-hidden=\"true\"><\/b><\/h2><\/div>\n\n\t\n  \n    <div class=\"row large-columns-3 medium-columns- small-columns-2 row-small slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  \n\t     <div class=\"product-small col has-hover product type-product post-1632 status-publish first instock product_cat-aconcagua-climb product_cat-adventure product_cat-day-tours product_cat-hiking-trekking product_cat-tours product_tag-4-nights product_tag-andes-range product_tag-mid-high-difficulty product_tag-private-tour has-post-thumbnail shipping-taxable product-type-variable\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t<div class=\"product-small box\">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/aventura-de-escalada-do-aconcagua-6-dias\/\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_portada-247x247.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Dois trekkers se abra\u00e7ando em alta altitude durante a caminhada \u2013 7 dias no Parque Aconc\u00e1gua \u2013 Plaza Francia + Plaza de Mulas + Bonete 5000m.\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_portada-247x247.webp 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_portada-400x400.webp 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_portada-280x280.webp 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_portada-768x768.webp 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_portada-12x12.webp 12w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_portada-510x510.webp 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_portada-100x100.webp 100w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_portada.webp 800w\" sizes=\"(max-width: 247px) 100vw, 247px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_1-247x247.webp\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"Lagoa andina refletindo as montanhas durante a caminhada \u2013 7 dias no Parque Aconc\u00e1gua \u2013 Plaza Francia + Plaza de Mulas + Bonete 5000m.\" aria-hidden=\"true\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_1-247x247.webp 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_1-400x400.webp 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_1-280x280.webp 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_1-768x768.webp 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_1-12x12.webp 12w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_1-510x510.webp 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_1-100x100.webp 100w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI07_1.webp 800w\" sizes=\"(max-width: 247px) 100vw, 247px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products\">\n\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tEscalada do Aconc\u00e1gua\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/aventura-de-escalada-do-aconcagua-6-dias\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Trekking de 7 dias no Aconc\u00e1gua at\u00e9 Plaza Francia, Plaza de Mulas + Subida ao Cerro Bonete 5000m<\/a><\/p><\/div><div class=\"price-wrapper\"><\/div><div class=\"add-to-cart-button\"><a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/aventura-de-escalada-do-aconcagua-6-dias\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1632\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_variable is-flat\" data-product_id=\"1632\" data-product_sku=\"LI07\" aria-label=\"Selecionar op\u00e7\u00f5es para &quot;7 Day Aconcagua Trekking to Plaza Francia, Plaza de Mulas + Ascent to Cerro Bonete 5000m&quot;\" rel=\"nofollow\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">Reserve agora<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1632\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div><div class=\"product-small col has-hover product type-product post-1624 status-publish instock product_cat-aconcagua-climb product_cat-adventure product_cat-day-tours product_cat-hiking-trekking product_cat-tours product_tag-andes-range product_tag-mid-high-difficulty product_tag-private-tour has-post-thumbnail shipping-taxable product-type-variable\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t<div class=\"product-small box\">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/expedicao-aconcagua-trekking-plaza-francia\/\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_2-247x247.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Caminhada em grupo com o Aconc\u00e1gua ao fundo durante o Trekking \u2013 3 dias no Parque Aconc\u00e1gua \u2013 Plaza Francia + excurs\u00e3o ao mirante da Parede Sul.\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_2-247x247.webp 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_2-400x400.webp 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_2-280x280.webp 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_2-768x768.webp 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_2-12x12.webp 12w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_2-510x510.webp 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_2-100x100.webp 100w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_2.webp 800w\" sizes=\"(max-width: 247px) 100vw, 247px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_3-247x247.webp\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"Trekkers comemorando em terreno nevado durante a excurs\u00e3o Trekking \u2013 3 dias no Parque Aconc\u00e1gua \u2013 Plaza Francia + Mirante da Parede Sul.\" aria-hidden=\"true\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_3-247x247.webp 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_3-400x400.webp 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_3-280x280.webp 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_3-768x768.webp 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_3-12x12.webp 12w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_3-510x510.webp 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_3-100x100.webp 100w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI06_3.webp 800w\" sizes=\"(max-width: 247px) 100vw, 247px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products\">\n\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tEscalada do Aconc\u00e1gua\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/expedicao-aconcagua-trekking-plaza-francia\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Trekking de 3 dias no Parque Aconc\u00e1gua at\u00e9 a Plaza Francia + mirante da parede sul<\/a><\/p><\/div><div class=\"price-wrapper\"><\/div><div class=\"add-to-cart-button\"><a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/expedicao-aconcagua-trekking-plaza-francia\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1624\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_variable is-flat\" data-product_id=\"1624\" data-product_sku=\"LI06\" aria-label=\"Selecionar op\u00e7\u00f5es para &quot;3 Day trekking in Aconcagua Park to Plaza Francia + South wall viewpoint&quot;\" rel=\"nofollow\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">Reserve agora<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1624\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div><\/div>\n\n<div class=\"row\"  id=\"row-822637804\">\n\n\n\t<div id=\"col-846911976\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p><span style=\"font-weight: 400;\">Em <strong>SAK Wine &amp; Travel<\/strong>, a gente cria experi\u00eancias no Aconc\u00e1gua para todos os n\u00edveis: desde expedi\u00e7\u00f5es de v\u00e1rias semanas at\u00e9 o cume pela Rota Normal at\u00e9 passeios de meio dia de caminhada leve que te colocam cara a cara com a montanha, sem escalada t\u00e9cnica. Todas as viagens saem de Mendoza, com guias locais especializados que conhecem o Aconc\u00e1gua t\u00e3o bem quanto os vinhedos do vale l\u00e1 embaixo.<\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-619025969\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-619025969 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >Caminhada pelo acampamento base do Aconc\u00e1gua<\/span><b aria-hidden=\"true\"><\/b><\/h2><\/div>\n\n\t\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-small\" >\n  \n\t     <div class=\"product-small col has-hover product type-product post-1183 status-publish last instock product_cat-aconcagua-climb product_cat-adventure product_cat-day-tours product_cat-hiking-trekking product_cat-tours product_tag-andes-range product_tag-full-day product_tag-mid-high-difficulty has-post-thumbnail shipping-taxable product-type-variable\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t<div class=\"product-small box\">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/trekking-aconcagua\/\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_2-247x247.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Caminhantes indo em dire\u00e7\u00e3o aos picos andinos durante a excurs\u00e3o Trekking Confluencia Base Camp \u2013 Parque Aconc\u00e1gua.\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_2-247x247.webp 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_2-400x400.webp 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_2-280x280.webp 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_2-768x768.webp 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_2-12x12.webp 12w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_2-510x510.webp 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_2-100x100.webp 100w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_2.webp 800w\" sizes=\"(max-width: 247px) 100vw, 247px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_3-247x247.webp\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"Placa na trilha mostrando as dist\u00e2ncias at\u00e9 o Acampamento Base da Conflu\u00eancia durante a excurs\u00e3o Trekking Acampamento Base da Conflu\u00eancia.\" aria-hidden=\"true\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_3-247x247.webp 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_3-400x400.webp 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_3-280x280.webp 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_3-768x768.webp 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_3-12x12.webp 12w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_3-510x510.webp 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_3-100x100.webp 100w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LI05_3.webp 800w\" sizes=\"(max-width: 247px) 100vw, 247px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products\">\n\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tEscalada do Aconc\u00e1gua\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/trekking-aconcagua\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Trekking ao Acampamento Conflu\u00eancia no Parque Aconc\u00e1gua<\/a><\/p><\/div><div class=\"price-wrapper\"><\/div><div class=\"add-to-cart-button\"><a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/trekking-aconcagua\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1183\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_variable is-flat\" data-product_id=\"1183\" data-product_sku=\"LI05\" aria-label=\"Selecionar op\u00e7\u00f5es para &quot;Trekking to the Confluencia Camp in Aconcagua Park&quot;\" rel=\"nofollow\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">Reserve agora<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1183\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div><\/div>\n\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >Caminhada leve at\u00e9 o mirante do Aconc\u00e1gua<\/span><b aria-hidden=\"true\"><\/b><\/h2><\/div>\n\n\t\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-small\" >\n  \n\t     <div class=\"product-small col has-hover product type-product post-7023 status-publish first instock product_cat-hiking-trekking product_cat-aconcagua-climb product_cat-adventure product_cat-day-tours product_cat-tours product_tag-andes-range product_tag-full-day product_tag-low-dificulty product_tag-small-group has-post-thumbnail featured shipping-taxable product-type-variable\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t<div class=\"product-small box\">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/excursao-para-pequenos-grupos-altos-andes-aconcagua\/\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_portada-247x247.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Duas mulheres tirando uma selfie no mirante do Aconc\u00e1gua com as montanhas ao fundo.\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_portada-247x247.webp 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_portada-400x400.webp 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_portada-280x280.webp 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_portada-768x768.webp 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_portada-12x12.webp 12w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_portada-510x510.webp 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_portada-100x100.webp 100w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_portada.webp 800w\" sizes=\"(max-width: 247px) 100vw, 247px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_1-247x247.webp\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"Vista distante do Aconc\u00e1gua a partir do sop\u00e9 dos Andes, em Mendoza.\" aria-hidden=\"true\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_1-247x247.webp 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_1-400x400.webp 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_1-280x280.webp 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_1-768x768.webp 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_1-12x12.webp 12w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_1-510x510.webp 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_1-100x100.webp 100w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA01_1.webp 800w\" sizes=\"(max-width: 247px) 100vw, 247px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products\">\n\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tCaminhadas e trekking\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/excursao-para-pequenos-grupos-altos-andes-aconcagua\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Excurs\u00e3o em grupo pequeno ao alto dos Andes at\u00e9 o mirante do Aconc\u00e1gua<\/a><\/p><\/div><div class=\"price-wrapper\"><\/div><div class=\"add-to-cart-button\"><a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/excursao-para-pequenos-grupos-altos-andes-aconcagua\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_7023\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_variable is-flat\" data-product_id=\"7023\" data-product_sku=\"GA01\" aria-label=\"Selecionar op\u00e7\u00f5es para &quot;Small group tour to the high Andes up to Aconcagua viewpoint&quot;\" rel=\"nofollow\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">Reserve agora<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_7023\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div><div class=\"product-small col has-hover product type-product post-7011 status-publish instock product_cat-hiking-trekking product_cat-aconcagua-climb product_cat-adventure product_cat-day-tours product_cat-tours product_tag-andes-range product_tag-full-day product_tag-low-dificulty product_tag-private-tour has-post-thumbnail featured shipping-taxable product-type-variable\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t<div class=\"product-small box\">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/excursao-particular-aos-altos-cumes-do-aconcagua\/\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_portada-247x247.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Viajante relaxando com os p\u00e9s para fora da janela do carro, com vista para a Cordilheira dos Andes, em Mendoza.\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_portada-247x247.webp 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_portada-400x400.webp 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_portada-280x280.webp 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_portada-768x768.webp 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_portada-12x12.webp 12w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_portada-510x510.webp 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_portada-100x100.webp 100w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_portada.webp 800w\" sizes=\"(max-width: 247px) 100vw, 247px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_1-247x247.webp\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"Montanhas Andes cobertas de neve com o Aconc\u00e1gua aparecendo ao fundo.\" aria-hidden=\"true\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_1-247x247.webp 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_1-400x400.webp 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_1-280x280.webp 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_1-768x768.webp 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_1-12x12.webp 12w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_1-510x510.webp 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_1-100x100.webp 100w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA02_1.webp 800w\" sizes=\"(max-width: 247px) 100vw, 247px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products\">\n\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tCaminhadas e trekking\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/excursao-particular-aos-altos-cumes-do-aconcagua\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Passeio particular ao alto dos Andes at\u00e9 o mirante do Aconc\u00e1gua<\/a><\/p><\/div><div class=\"price-wrapper\"><\/div><div class=\"add-to-cart-button\"><a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/excursao-particular-aos-altos-cumes-do-aconcagua\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_7011\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_variable is-flat\" data-product_id=\"7011\" data-product_sku=\"GA02\" aria-label=\"Selecionar op\u00e7\u00f5es para &quot;Private tour to the high Andes up to Aconcagua viewpoint&quot;\" rel=\"nofollow\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">Reserve agora<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_7011\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div><div class=\"product-small col has-hover product type-product post-1150 status-publish last instock product_cat-hiking-trekking product_cat-aconcagua-climb product_cat-adventure product_cat-day-tours product_cat-tours product_tag-andes-range product_tag-full-day product_tag-low-dificulty product_tag-small-group has-post-thumbnail featured shipping-taxable product-type-variable\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t<div class=\"product-small box\">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/caminhada-no-aconcagua-para-grupos-pequenos\/\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_portada-247x247.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Dois viajantes tirando foto com o Aconc\u00e1gua ao fundo durante uma excurs\u00e3o nas montanhas em Mendoza.\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_portada-247x247.webp 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_portada-400x400.webp 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_portada-280x280.webp 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_portada-768x768.webp 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_portada-12x12.webp 12w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_portada-510x510.webp 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_portada-100x100.webp 100w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_portada.webp 800w\" sizes=\"(max-width: 247px) 100vw, 247px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_1-247x247.webp\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"Puente del Inca, uma forma\u00e7\u00e3o rochosa natural com cores minerais nos Andes de Mendoza.\" aria-hidden=\"true\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_1-247x247.webp 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_1-400x400.webp 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_1-280x280.webp 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_1-768x768.webp 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_1-12x12.webp 12w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_1-510x510.webp 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_1-100x100.webp 100w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/GA03_1.webp 800w\" sizes=\"(max-width: 247px) 100vw, 247px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products\">\n\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tCaminhadas e trekking\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/caminhada-no-aconcagua-para-grupos-pequenos\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Visita \u00e0 Cordilheira dos Andes com trilha para a Quebrada del Durazno - SPVD<\/a><\/p><\/div><div class=\"price-wrapper\"><\/div><div class=\"add-to-cart-button\"><a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/caminhada-no-aconcagua-para-grupos-pequenos\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1150\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_variable is-flat\" data-product_id=\"1150\" data-product_sku=\"GA03\" aria-label=\"Selecionar op\u00e7\u00f5es para &quot;Visit to the high Andes with trekking to Quebrada del Durazno - SPVD&quot;\" rel=\"nofollow\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">Reserve agora<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1150\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div><div class=\"product-small col has-hover product type-product post-7005 status-publish first instock product_cat-hiking-trekking product_cat-aconcagua-climb product_cat-adventure product_cat-day-tours product_cat-tours product_tag-andes-range product_tag-full-day product_tag-low-dificulty product_tag-private-tour has-post-thumbnail featured shipping-taxable product-type-variable\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t<div class=\"product-small box\">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/tour-altas-cumbres-trekking-quebrada-durazno\/\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_portada-247x247.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Viajante curtindo a paisagem andina pela janela do carro na Rota das Altas Montanhas, em Mendoza.\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_portada-247x247.webp 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_portada-400x400.webp 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_portada-280x280.webp 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_portada-768x768.webp 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_portada-12x12.webp 12w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_portada-510x510.webp 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_portada-100x100.webp 100w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_portada.webp 800w\" sizes=\"(max-width: 247px) 100vw, 247px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"247\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_2-247x247.webp\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"Grupo de caminhantes se aproximando do Aconc\u00e1gua, com a montanha dominando o fundo.\" aria-hidden=\"true\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_2-247x247.webp 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_2-400x400.webp 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_2-280x280.webp 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_2-768x768.webp 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_2-12x12.webp 12w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_2-510x510.webp 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_2-100x100.webp 100w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/GA04_2.webp 800w\" sizes=\"(max-width: 247px) 100vw, 247px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products\">\n\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tCaminhadas e trekking\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/tour-altas-cumbres-trekking-quebrada-durazno\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Excurs\u00e3o privativa ao alto dos Andes com caminhada at\u00e9 a Quebrada del Durazno<\/a><\/p><\/div><div class=\"price-wrapper\"><\/div><div class=\"add-to-cart-button\"><a href=\"https:\/\/sakwinetravel.com\/pt\/mendoza-tours\/tour-altas-cumbres-trekking-quebrada-durazno\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_7005\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_variable is-flat\" data-product_id=\"7005\" data-product_sku=\"GA04\" aria-label=\"Selecionar op\u00e7\u00f5es para &quot;Private tour to the high Andes with trekking to the Quebrada del Durazno&quot;\" rel=\"nofollow\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">Reserve agora<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_7005\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div><\/div>\n\n<div class=\"row\"  id=\"row-496187966\">\n\n\n\t<div id=\"col-1612284013\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-704845363\">\n\n\n\t<div id=\"col-602732259\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1587539900\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1587539900 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h3 style=\"text-align: left;\"><strong>Escolha sua experi\u00eancia no Aconc\u00e1gua<\/strong><\/h3>\n<p style=\"text-align: left;\"><span style=\"font-weight: 400;\">Seja para conquistar um dos Sete Cumes ou simplesmente para sentir a altitude dos altos Andes, h\u00e1 uma excurs\u00e3o ao Aconc\u00e1gua adequada ao seu n\u00edvel de condicionamento f\u00edsico, cronograma e or\u00e7amento.<\/span><\/p>\n<p style=\"text-align: left;\">\u00a0<\/p>\n<table>\n<tbody>\n<tr>\n<td>\n<p><b>Passeio<\/b><\/p>\n<\/td>\n<td>\n<p><b>Tipo<\/b><\/p>\n<\/td>\n<td>\n<p><b>Dura\u00e7\u00e3o<\/b><\/p>\n<\/td>\n<td>\n<p><b>N\u00edvel<\/b><\/p>\n<\/td>\n<td>\n<p><b>Tentativa de chegar ao cume<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><span style=\"font-weight: 400;\">Cume \u2014 Rota Normal<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">Expedi\u00e7\u00e3o<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">21 dias<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">Avan\u00e7ado<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">Sim<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><span style=\"font-weight: 400;\">Expedi\u00e7\u00e3o pela Rota 360<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">Expedi\u00e7\u00e3o<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">Consulte-nos<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">Avan\u00e7ado<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">Sim<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><span style=\"font-weight: 400;\">Caminhada de 7 dias \u2014 Plaza Francia + Mulas<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">Trekking<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">7 dias<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">Intermedi\u00e1rio<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">N\u00e3o (m\u00e1x. 5.000 m)<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><span style=\"font-weight: 400;\">Caminhada de 3 dias \u2014 Parede Sul<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">Trekking<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">3 dias<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">Moderado<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">N\u00e3o<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><span style=\"font-weight: 400;\">Caminhada at\u00e9 o Acampamento Base de Confluencia<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">Caminhada de um dia<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">1 dia<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">F\u00e1cil\/Moderado<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">N\u00e3o<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><span style=\"font-weight: 400;\">Caminhada leve at\u00e9 o mirante (em grupo)<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">Excurs\u00e3o<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">1 dia<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">F\u00e1cil<\/span><\/p>\n<\/td>\n<td>\n<p><span style=\"font-weight: 400;\">N\u00e3o<\/span><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">\n<p><span style=\"font-weight: 400;\">Caminhada leve at\u00e9 o mirante (privado)<\/span><\/p>\n<\/td>\n<td style=\"text-align: left;\">\n<p><span style=\"font-weight: 400;\">Excurs\u00e3o<\/span><\/p>\n<\/td>\n<td style=\"text-align: left;\">\n<p><span style=\"font-weight: 400;\">1 dia<\/span><\/p>\n<\/td>\n<td style=\"text-align: left;\">\n<p><span style=\"font-weight: 400;\">F\u00e1cil<\/span><\/p>\n<\/td>\n<td>\n<p style=\"text-align: left;\"><span style=\"font-weight: 400;\">N\u00e3o<\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-997516615\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-997516615 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >EXTENS\u00d5ES PARA SUAS EXPEDI\u00c7\u00d5ES AO ACONC\u00c1GUA<\/span><b aria-hidden=\"true\"><\/b><\/h2><\/div>\n\n<p data-start=\"769\" data-end=\"1057\">Sua jornada n\u00e3o termina no Aconc\u00e1gua. Depois de concluir uma <a href=\"https:\/\/sakwinetravel.com\/pt\/pacotes-em-mendoza\/escalar-o-aconcagua\/caminhada-no-acampamento-base\/\">Caminhada at\u00e9 o acampamento base do Aconc\u00e1gua<\/a>, descubra os vinhedos mundialmente famosos de Mendoza, curta passeios gastron\u00f4micos ou embarque em outras aventuras em altitude. Cada experi\u00eancia complementa a sua <strong>Tour do Aconc\u00e1gua<\/strong>Voc\u00ea pode ver a imagem de um dos mais belos hot\u00e9is do mundo, revelando outra camada dessa regi\u00e3o not\u00e1vel.<\/p>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >OUTRAS CATEGORIAS DE PACOTES<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n<div class=\"row\"  id=\"row-1171561742\">\n\n\n\t<div id=\"col-944356434\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/sakwinetravel.com\/pt\/pacotes-em-mendoza\/passeios-aventura\/\">\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LH01_portada.webp\" class=\"attachment- size-\" alt=\"Cara escalando uma parede de pedra vertical em Potrerillos, Mendoza.\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LH01_portada.webp 800w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LH01_portada-400x400.webp 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LH01_portada-280x280.webp 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LH01_portada-768x768.webp 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LH01_portada-12x12.webp 12w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LH01_portada-247x247.webp 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LH01_portada-510x510.webp 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/LH01_portada-100x100.webp 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>AVENTURA<\/h3>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1285121234\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/sakwinetravel.com\/pt\/pacotes-em-mendoza\/viagens-de-3-dias\/\">\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/IA03_2.webp\" class=\"attachment- size-\" alt=\"Cozinha regional e churrasco - Experi\u00eancia Finca San Ignacio\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/IA03_2.webp 800w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/IA03_2-400x400.webp 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/IA03_2-280x280.webp 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/IA03_2-768x768.webp 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/IA03_2-12x12.webp 12w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/IA03_2-247x247.webp 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/IA03_2-510x510.webp 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2023\/06\/IA03_2-100x100.webp 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>PACOTES DE 3 DIAS<\/h3>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-521366509\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/sakwinetravel.com\/pt\/pacotes-em-mendoza\/viagens-personalizadas\/\">\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/11\/vistalba.jpg\" class=\"attachment- size-\" alt=\"Vin\u00edcola Vistalba\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/11\/vistalba.jpg 600w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/11\/vistalba-400x400.jpg 400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/11\/vistalba-280x280.jpg 280w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/11\/vistalba-247x247.jpg 247w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/11\/vistalba-510x510.jpg 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/11\/vistalba-100x100.jpg 100w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>PASSEIOS PERSONALIZADOS<\/h3>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2022052126\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/sakwinetravel.com\/pt\/pacotes-em-mendoza\/viagens-de-luxo\/\">\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1360\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2018\/12\/DSC_2100.jpg\" class=\"attachment- size-\" alt=\"Passeios de vinho em Mendoza hotel de luxo\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2018\/12\/DSC_2100.jpg 2048w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2018\/12\/DSC_2100-510x339.jpg 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2018\/12\/DSC_2100-602x400.jpg 602w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2018\/12\/DSC_2100-768x510.jpg 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2018\/12\/DSC_2100-1205x800.jpg 1205w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h3>VIAGENS DE LUXO<\/h3>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-1840951227\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1840951227 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\"  id=\"row-878358861\">\n\n\n\t<div id=\"col-2096107530\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3 style=\"text-align: left;\"><strong>Sobre o Aconc\u00e1gua: O Telhado das Am\u00e9ricas<\/strong><\/h3>\n<p style=\"text-align: left;\">O Aconc\u00e1gua chega a 6.962 metros (22.841 p\u00e9s) no cora\u00e7\u00e3o dos Andes argentinos, dentro do Parque Provincial do Aconc\u00e1gua, em Mendoza. \u00c9 o pico mais alto do Hemisf\u00e9rio Ocidental, do Hemisf\u00e9rio Sul e uma das Sete Cimas: as montanhas mais altas de cada um dos sete continentes.<br \/>A montanha oferece v\u00e1rias rotas at\u00e9 o cume. A Rota Normal, que parte do noroeste, \u00e9 a mais popular e considerada n\u00e3o t\u00e9cnica, embora a altitude, o frio e o vento a tornem uma aventura s\u00e9ria. A Travessia Polonesa e a Rota 360 oferecem maior desafio e recompensa para alpinistas experientes. A Parede Sul \u00e9 considerada uma das faces mais exigentes dos Andes.<br \/>A temporada de escalada vai de meados de novembro at\u00e9 o final de fevereiro, sendo que janeiro oferece as janelas clim\u00e1ticas mais est\u00e1veis. Todos os alpinistas e trekkers que entrarem no Parque Provincial do Aconc\u00e1gua precisam de uma autoriza\u00e7\u00e3o oficial emitida pelo governo provincial de Mendoza. Os custos das autoriza\u00e7\u00f5es variam de acordo com a \u00e9poca do ano e a rota: as autoriza\u00e7\u00f5es para chegar ao cume na alta temporada costumam custar entre US$ 1.000 e US$ 1.400 por pessoa. A SAK Wine &amp; Travel d\u00e1 orienta\u00e7\u00f5es sobre as autoriza\u00e7\u00f5es como parte de todos os pacotes de expedi\u00e7\u00e3o.<\/p>\n<h3 style=\"text-align: left;\"><strong>Por que escalar o Aconc\u00e1gua com a SAK?<\/strong><\/h3>\n<p style=\"text-align: left;\">Existem operadoras internacionais que organizam expedi\u00e7\u00f5es ao Aconc\u00e1gua a partir de Seattle e da Nova Zel\u00e2ndia. N\u00f3s as organizamos a partir de Mendoza. Essa diferen\u00e7a \u00e9 mais importante do que parece.<br \/>Nossos guias cresceram vendo essa montanha. Eles sabem em quais condi\u00e7\u00f5es clim\u00e1ticas confiar e quais \u00e9 melhor esperar passar, quais locais de acampamento oferecem melhor prote\u00e7\u00e3o contra o vento na noite do cume e como identificar os sinais de mal-estar causados pela altitude antes que se tornem um problema. O conhecimento local n\u00e3o \u00e9 um detalhe: a 6.962 metros, \u00e9 a diferen\u00e7a entre voltar em seguran\u00e7a e chegar ao cume.<br \/>A SAK tamb\u00e9m \u00e9 uma empresa pequena por op\u00e7\u00e3o. Voc\u00ea n\u00e3o vai ficar num grupo de vinte pessoas. Vai conhecer seus guias pelo nome antes mesmo do fim do primeiro dia. E quando a expedi\u00e7\u00e3o acabar, ou at\u00e9 mesmo como uma extens\u00e3o, a regi\u00e3o vin\u00edcola de Mendoza est\u00e1 bem ali te esperando, algo que nenhuma operadora de Seattle pode oferecer.<br \/>Atuamos de acordo com o Legajo 14434, Disposi\u00e7\u00e3o 241\/2010, e estamos comprometidos com o turismo sustent\u00e1vel por meio do nosso programa SAK IN Action, que garante que cada passeio contribua para a conserva\u00e7\u00e3o das paisagens pelas quais te levamos.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t<section class=\"section\" id=\"section_144381787\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(235, 235, 235);border-width:1px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-large align-middle align-center\"  id=\"row-421552448\">\n\n\n\t<div id=\"col-1012760428\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center dark\"  >\n\t\t\t\n\t\t\t\n\n<p>&nbsp;<\/p>\n<h2>Move For Life<\/h2>\n<p>Como decidimos ser sustent\u00e1veis, viajar conosco contribui para um mundo melhor. Encontre mais informa\u00e7\u00f5es aqui.<\/p>\n\t<div id=\"gap-301799214\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-301799214 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"gap-1001732807\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1001732807 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a href=\"https:\/\/sakinaction.sakwinetours.tur.ar\" target=\"_blank\" class=\"button primary is-outline\" rel=\"noopener nofollow\" style=\"border-radius:10px;\">\n\t\t<span>leia mais<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-122216878\" class=\"col medium-6 small-12 large-6\"  data-animate=\"flipInY\">\n\t\t\t\t<div class=\"col-inner text-center box-shadow-2 box-shadow-5-hover\" style=\"background-color:rgb(137, 21, 21);\" >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1687295876\">\n\t\t<a class=\"\" href=\"https:\/\/sakinaction.sakwinetours.tur.ar\" target=\"_blank\" rel=\"noopener nofollow\">\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1020\" height=\"527\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2021\/06\/marca-sakinaction_crema-1400x723.png\" class=\"attachment-large size-large\" alt=\"logotipo da sak in action bege\" srcset=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2021\/06\/marca-sakinaction_crema-1400x723.png 1400w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2021\/06\/marca-sakinaction_crema-775x400.png 775w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2021\/06\/marca-sakinaction_crema-768x397.png 768w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2021\/06\/marca-sakinaction_crema-1536x793.png 1536w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2021\/06\/marca-sakinaction_crema-510x263.png 510w, https:\/\/sakwinetravel.com\/wp-content\/uploads\/2021\/06\/marca-sakinaction_crema.png 1774w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1687295876 {\n  width: 68%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-122216878 > .col-inner {\n  padding: 15px 15px 15px 15px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_144381787 {\n  padding-top: 59px;\n  padding-bottom: 59px;\n  min-height: 300px;\n  background-color: rgb(171, 171, 171);\n}\n#section_144381787 .section-bg-overlay {\n  background-color: rgba(224, 158, 51, 0.64);\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-914028660\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-914028660 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h3 style=\"text-align: left;\"><b>Aproveite ainda mais sua experi\u00eancia no Aconc\u00e1gua<\/b><\/h3>\n<p style=\"text-align: left;\"><span style=\"font-weight: 400;\">Os Andes n\u00e3o terminam nos limites do parque, e o mesmo vale para tudo o que Mendoza tem a oferecer. Muitos dos nossos clientes combinam uma excurs\u00e3o ao Aconc\u00e1gua com uma ou mais dessas experi\u00eancias:<\/span><\/p>\n<ul style=\"text-align: left;\">\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Passeios enol\u00f3gicos em Mendoza, em Luj\u00e1n de Cuyo e no Vale do Uco: degusta\u00e7\u00f5es particulares nas melhores vin\u00edcolas, acompanhadas de almo\u00e7os gourmet<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Passeio pela cidade de Mendoza e o Labirinto de Borges<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Pacotes de luxo de v\u00e1rios dias que combinam aventura nas montanhas com hospedagem em vin\u00edcolas de alto padr\u00e3o<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Passeios a cavalo, ciclismo e rafting no sop\u00e9 das montanhas de Mendoza<\/span><\/li>\n<\/ul>\n<p style=\"text-align: left;\"><span style=\"font-weight: 400;\">Depois de passar alguns dias em altitude, a ideia de uma mesa grande numa vin\u00edcola do Vale do Uco parece bem diferente. Achamos que \u00e9 assim mesmo. Pede pra gente montar a combina\u00e7\u00e3o perfeita pra sua viagem.<\/span><\/p>\n\t<div id=\"gap-1672774107\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1672774107 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h3 style=\"text-align: center;\">VOC\u00ca GOSTARIA DE VER MAIS?<\/h3>\n\t<div id=\"gap-793159255\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-793159255 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section\" id=\"section_1276835016\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(235, 235, 235);border-width:1px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-large align-middle align-center\"  id=\"row-719925089\">\n\n\n\t<div id=\"col-1104750764\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center dark\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >explore os passeios de um dia<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n<p>Se n\u00e3o estiver certo de reservar um pacote, mas ainda assim quiser ver passeios de um dia, consulte esta se\u00e7\u00e3o e encontre os melhores passeios em Mendoza. Veja servi\u00e7os particulares ou para pequenos grupos.&nbsp;<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-968613813\" class=\"col medium-6 small-12 large-6\"  data-animate=\"flipInY\">\n\t\t\t\t<div class=\"col-inner text-left box-shadow-2 box-shadow-5-hover\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-2014945928\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img fetchpriority=\"high\" decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/sakwinetravel.com\/wp-content\/uploads\/2019\/10\/cooking-2.jpg\" class=\"bg attachment-large size-large\" alt=\"aula de culin\u00e1ria de asado\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"https:\/\/sakwinetravel.com\/pt\/passeios-de-um-dia-em-mendoza\/\"><div class=\"fill banner-link\"><\/div><\/a>            \n\n   <div id=\"text-box-1387407123\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h3 class=\"uppercase\"><strong>IR PARA passeios diurnos<\/strong><\/h3>\n<p>Se estiver procurando por experi\u00eancias inesquec\u00edveis, v\u00e1 para esta se\u00e7\u00e3o!<\/p>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1387407123 {\n  width: 60%;\n}\n#text-box-1387407123 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2014945928 {\n  padding-top: 300px;\n}\n#banner-2014945928 .banner-bg img {\n  object-position: 48% 43%;\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-968613813 > .col-inner {\n  padding: 15px 15px 15px 15px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1276835016 {\n  padding-top: 59px;\n  padding-bottom: 59px;\n  min-height: 300px;\n  background-color: #bd1d1d;\n}\n#section_1276835016 .section-bg-overlay {\n  background-color: rgba(0, 0, 0, 0.64);\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-2089285584\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2089285584 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-235731219\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-235731219 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\"  id=\"row-97909609\">\n\n\n\t<div id=\"col-729903908\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3><b>Requisitos f\u00edsicos e pr\u00e9-requisitos<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">O Aconc\u00e1gua exige uma prepara\u00e7\u00e3o s\u00e9ria. A Rota Normal n\u00e3o \u00e9 tecnicamente dif\u00edcil: voc\u00ea n\u00e3o precisa de cordas, machados de gelo nem treinamento para lidar com fendas no gelo. Mas a altitude \u00e9 real, e por mais experi\u00eancia que voc\u00ea tenha em altitudes mais baixas, nada te prepara totalmente para a forma como o corpo reage acima dos 6.000 metros.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para expedi\u00e7\u00f5es a picos, a gente recomenda:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Experi\u00eancia pr\u00e9via em altitudes acima de 4.500 metros (14.800 p\u00e9s)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Boa prepara\u00e7\u00e3o cardiovascular (de prefer\u00eancia, 5 a 6 dias por semana de treino aer\u00f3bico cont\u00ednuo por pelo menos 3 meses antes da partida)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Experi\u00eancia em caminhadas de v\u00e1rios dias com mochila cheia<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Conhecimento sobre acampamento em climas frios e sistemas de camadas de roupa<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Para caminhadas de v\u00e1rios dias (3 e 7 dias), basta ter um condicionamento f\u00edsico moderado e alguma experi\u00eancia em trilhas. Para passeios de trekking leve, n\u00e3o \u00e9 preciso nenhuma prepara\u00e7\u00e3o especial al\u00e9m de boa sa\u00fade em geral.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea n\u00e3o tiver certeza se um passeio espec\u00edfico \u00e9 adequado para o seu n\u00edvel de condicionamento f\u00edsico atual, entre em contato conosco. Preferimos te ajudar a escolher a experi\u00eancia certa do que ver voc\u00ea desistir frustrado.<\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t<section class=\"section\" id=\"section_572132210\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-759166511\">\n\n\n\t<div id=\"col-1196466922\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-1320099970\">\n\n\n\t<div id=\"col-1193255539\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2><b>Perguntas frequentes<\/b><\/h2>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"accordion\">\n\n\t<div id=\"accordion-3960113842\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3960113842-label\" class=\"accordion-title plain\" href=\"#accordion-item-how-hard-is-it-to-climb-aconcagua?\" aria-expanded=\"false\" aria-controls=\"accordion-3960113842-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Alternar\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>\u00c9 dif\u00edcil escalar o Aconc\u00e1gua?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3960113842-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3960113842-label\">\n\t\t\t\n\n<p><span style=\"font-weight: 400;\">O Aconc\u00e1gua \u00e9 uma escalada n\u00e3o t\u00e9cnica pela Rota Normal, sem necessidade de cordas nem escalada no gelo. Mas, a quase 7.000 metros, s\u00f3 a altitude j\u00e1 faz disso um desafio s\u00e9rio. Voc\u00ea vai precisar de boa resist\u00eancia aer\u00f3bica, experi\u00eancia pr\u00e9via em altitudes acima de 4.500 metros e tempo reservado no seu itiner\u00e1rio para uma aclimata\u00e7\u00e3o adequada. A montanha \u00e9 totalmente alcan\u00e7\u00e1vel para trekkers motivados e bem preparados que sejam sinceros quanto \u00e0 sua prepara\u00e7\u00e3o. N\u00e3o \u00e9 um passeio para quem s\u00f3 faz trilhas nos fins de semana.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3390292519\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3390292519-label\" class=\"accordion-title plain\" href=\"#accordion-item-what-is-the-best-season-to-climb-aconcagua?\" aria-expanded=\"false\" aria-controls=\"accordion-3390292519-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Alternar\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Qual \u00e9 a melhor \u00e9poca para escalar o Aconc\u00e1gua?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3390292519-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3390292519-label\">\n\t\t\t\n\n<p><span style=\"font-weight: 400;\">A temporada oficial de escalada e trekking vai de meados de novembro at\u00e9 o final de fevereiro, e o parque encerra a emiss\u00e3o de novas autoriza\u00e7\u00f5es no final de fevereiro. Janeiro \u00e9 amplamente considerado o melhor m\u00eas para tentar chegar ao cume, j\u00e1 que oferece as janelas de bom tempo mais consistentes. O in\u00edcio e o final da temporada podem trazer condi\u00e7\u00f5es mais inst\u00e1veis e temperaturas mais baixas.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3242165679\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3242165679-label\" class=\"accordion-title plain\" href=\"#accordion-item-how-much-does-it-cost-to-climb-aconcagua?\" aria-expanded=\"false\" aria-controls=\"accordion-3242165679-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Alternar\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Quanto custa escalar o Aconc\u00e1gua?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3242165679-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3242165679-label\">\n\t\t\t\n\n<p><span style=\"font-weight: 400;\">Uma expedi\u00e7\u00e3o totalmente guiada at\u00e9 o cume do Aconc\u00e1gua geralmente custa entre US$ 4.000 e US$ 8.000 ou mais, dependendo do n\u00edvel de servi\u00e7o, da propor\u00e7\u00e3o de guias por participante e da dura\u00e7\u00e3o. As licen\u00e7as do parque para tentativas de escalada no pico, na alta temporada, custam cerca de US$ 1.000 a US$ 1.400 por pessoa, pagas diretamente ao governo provincial de Mendoza. Passeios de trekking mais curtos (caminhadas at\u00e9 o acampamento base, trilhas de v\u00e1rios dias e trekking leve) s\u00e3o bem mais acess\u00edveis. Fala com a gente para saber os pre\u00e7os atualizados de qualquer passeio espec\u00edfico.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1640034576\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1640034576-label\" class=\"accordion-title plain\" href=\"#accordion-item-do-i-need-a-permit-to-climb-aconcagua?\" aria-expanded=\"false\" aria-controls=\"accordion-1640034576-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Alternar\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Preciso de uma autoriza\u00e7\u00e3o para escalar o Aconc\u00e1gua?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1640034576-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1640034576-label\">\n\t\t\t\n\n<p><span style=\"font-weight: 400;\">Sim. Qualquer pessoa que entre no Parque Provincial do Aconc\u00e1gua, seja para uma caminhada de um dia at\u00e9 Confluencia ou para uma tentativa completa de chegar ao cume, precisa de uma autoriza\u00e7\u00e3o oficial emitida pelo governo de Mendoza. As categorias de autoriza\u00e7\u00e3o variam de acordo com a rota e a dura\u00e7\u00e3o, sendo que as autoriza\u00e7\u00f5es para o cume s\u00e3o as mais caras. A SAK Wine &amp; Travel te orienta sobre como conseguir a autoriza\u00e7\u00e3o certa para o passeio que voc\u00ea escolheu e pode te ajudar com o processo como parte da sua reserva.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_572132210 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":7469,"parent":6244,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7741","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"bsf-aiosrs-schema-type":null,"bsf-aiosrs-local-business":null,"bsf-aiosrs-schema-location":null,"bsf-aiosrs-product":null,"bsf-aiosrs-faq":null,"bsf-aiosrs-schema-exclusion":null,"bsf-aiosrs-article":null,"bsf-aiosrs-custom-markup":null,"_wp_attached_file":null,"_wp_attachment_metadata":null,"_wp_attachment_image_alt":null,"resmushed_quality":null,"wpml_media_processed":null,"litespeed-optimize-set":null,"litespeed-optimize-size":null,"original-file":null,"smush-complete":null,"smush-info":null,"smush-stats":null,"_wp_attachment_backup_sizes":null,"_wp_attachment_context":null,"_wpml_media_usage":null,"wp-smpro-smush-data":null,"resmushed_cumulated_original_sizes":null,"resmushed_cumulated_optimized_sizes":null,"_flatsome_studio_id":null,"_oembed_d58779b860128261e753fe97981175ea":null,"resmushed_disabled":null,"_yoast_wpseo_primary_block_categories":null,"_icl_translator_note":null,"br_product_tab":null,"br_tabs_location":null,"_yoast_wpseo_primary_featured_item_category":null,"_oembed_7298dca11798b55ac013356926f8b0e9":null,"_oembed_time_7298dca11798b55ac013356926f8b0e9":null,"_oembed_90486f14e048368c828685347d0f145f":null,"_oembed_time_90486f14e048368c828685347d0f145f":null,"_menu_item_type":null,"_menu_item_menu_item_parent":null,"_menu_item_object_id":null,"_menu_item_object":null,"_menu_item_target":null,"_menu_item_classes":null,"_menu_item_xfn":null,"_menu_item_url":null,"_menu_item_orphaned":null,"_menu_item_design":null,"_menu_item_width":null,"_menu_item_height":null,"_menu_item_block":null,"_menu_item_behavior":null,"_menu_item_icon-type":null,"_menu_item_icon-id":null,"_menu_item_icon-width":null,"_menu_item_icon-height":null,"_menu_item_icon-html":null,"faq-8478-question-answer-fieldtype":"","faq-8478-question-answer":[{"question":"","answer":""}],"_yoast_wpseo_meta-robots-noindex":null,"custom-markup-9611-custom-markup-fieldtype":"custom-field","custom-markup-9611-custom-markup":"","_oembed_97120786a5d618011442f73be26e093f":null,"_oembed_time_97120786a5d618011442f73be26e093f":null,"_yoast_wpseo_schema_page_type":"WebPage","_yoast_wpseo_meta-robots-nofollow":null,"_yoast_post_redirect_info":{"origin":"wine-tours","target":"mendoza-tours","type":301,"format":"plain"},"_wp_desired_post_slug":null,"data_version":null,"popup_open_count":null,"popup_title":null,"popup_settings":null,"popup_open_count_total":null,"popup_last_opened":null,"popup_conversion_count":null,"enabled":null,"_pum_built_in":null,"_pum_default_theme":null,"popup_theme_data_version":null,"popup_theme_settings":null,"_yoast_wpseo_primary_category":null,"_product_attributes":null,"_mp_recurring_is_recurrent":null,"_mp_recurring_frequency":null,"_mp_recurring_frequency_type":null,"_mp_recurring_end_date":null,"wc_productdata_options":null,"_product_image_gallery":null,"_yoast_wpseo_primary_product_cat":null,"wpseo_global_identifier_values":null,"product-8476-name-fieldtype":null,"product-8476-name":null,"product-8476-brand-name-fieldtype":null,"product-8476-brand-name":null,"product-8476-image-fieldtype":null,"product-8476-image":null,"product-8476-url-fieldtype":null,"product-8476-url":null,"product-8476-description-fieldtype":null,"product-8476-description":null,"product-8476-sku-fieldtype":null,"product-8476-sku":null,"product-8476-mpn-fieldtype":null,"product-8476-mpn":null,"product-8476-avail-fieldtype":null,"product-8476-avail":null,"product-8476-price-valid-until-fieldtype":null,"product-8476-price-valid-until":null,"product-8476-price-fieldtype":null,"product-8476-price":null,"product-8476-currency-fieldtype":null,"product-8476-currency":null,"product-8476-product-review-fieldtype":null,"product-8476-product-review":null,"product-8476-rating-fieldtype":null,"product-8476-rating":null,"product-8476-review-count-fieldtype":null,"product-8476-review-count":null,"common_tab_tab_custom_title":null,"_common_tab_tab_custom_title":null,"common_tab":null,"_common_tab":null,"tab-test_tab_custom_title":null,"_tab-test_tab_custom_title":null,"tab-test":null,"_tab-test":null,"_sku":null,"_yoast_wpseo_primary_product_brand":null,"_yoast_wpseo_is_cornerstone":null,"_yoast_wpseo_bctitle":null,"_wc_rating_count":null,"_sale_price_dates_from":null,"_sale_price_dates_to":null,"_weight":null,"_length":null,"_width":null,"_height":null,"_upsell_ids":null,"_purchase_note":null,"_default_attributes":null,"_yoast_wpseo_canonical":null,"_oembed_2d5a7487ae0473fcdbf1790ea8685d81":null,"_oembed_time_2d5a7487ae0473fcdbf1790ea8685d81":null,"_oembed_70b09ca87cd1357c2b1fe1287cbaa5f0":null,"_oembed_time_70b09ca87cd1357c2b1fe1287cbaa5f0":null,"_wpml_post_translation_editor_native":null,"wcml_sync_hash":null,"attr_label_translations":null,"_children":null,"_wcml_average_rating":null,"_wcml_review_count":null,"_oembed_2b467c9fde81cceadb8d2b5aee4202f4":null,"_oembed_time_2b467c9fde81cceadb8d2b5aee4202f4":null,"_oembed_be7d14c7423fe070b6b0b24e60767975":null,"_oembed_time_be7d14c7423fe070b6b0b24e60767975":null,"saswp_modify_this_schema_8457":null,"saswp_trip_schema_id_8457":null,"saswp_trip_schema_name_8457":null,"saswp_trip_schema_description_8457":null,"saswp_trip_schema_url_8457":null,"saswp_trip_schema_image_8457_detail":null,"saswp_trip_schema_image_8457":null,"use_for_all_products":null,"_use_for_all_products":null,"priority":null,"_priority":null,"default_content":null,"_default_content":null,"content_header":null,"_content_header":null,"content_footer":null,"_content_footer":null,"_variation_description":null,"attribute_pa_tour-mode-tour":null,"attribute_pa_group-size":null,"_booking_lockout_field":null,"attribute_pa_tastings-tour":null,"attribute_pa_where-ir-your-hotel-located":null,"attribute_location":null,"_sale_price":null,"attribute_pa_select-hotel-pkt":null,"attribute_pa_occupancy":null,"attribute_pa_optionals":null,"attribute_pa_location":null,"saswp_schema_type_product_pros_enable_cons":null,"schema_type":null,"saswp_enable_speakable_schema":null,"saswp_enable_videoobject":null,"saswp_enable_append_reviews":null,"saswp_enable_itemlist_schema":null,"saswp_item_list_custom":null,"saswp_attahced_reviews":null,"saswp_attached_collection":null,"saswp_enable_faq_schema":null,"data_group_array":null,"discount_type":null,"coupon_amount":null,"individual_use":null,"product_ids":null,"exclude_product_ids":null,"usage_limit":null,"usage_limit_per_user":null,"limit_usage_to_x_items":null,"usage_count":null,"date_expires":null,"expiry_date":null,"free_shipping":null,"product_categories":null,"exclude_product_categories":null,"exclude_sale_items":null,"minimum_amount":null,"maximum_amount":null,"customer_email":null,"_used_by":null,"_order_key":null,"_customer_user":null,"_payment_method":null,"_payment_method_title":null,"_customer_ip_address":null,"_customer_user_agent":null,"_created_via":null,"_cart_hash":null,"_billing_first_name":null,"_billing_last_name":null,"_billing_address_1":null,"_billing_city":null,"_billing_postcode":null,"_billing_country":null,"_billing_email":null,"_billing_phone":null,"_billing_address_index":null,"_shipping_address_index":null,"is_vat_exempt":null,"order_booking_status":null,"wpml_language":null,"_billing_state":null,"_used_gateway":null,"_billing_address_2":null,"_billing_company":null,"is_production_mode":null,"Email del comprador":null,"Tipo de m\u00e9todo de pago":null,"M\u00e9todo de pago":null,"Mercado Pago - Payment 19196025087":null,"_Mercado_Pago_Payment_IDs":null,"_date_paid":null,"_paid_date":null,"_download_permissions_granted":null,"_recorded_sales":null,"_recorded_coupon_usage_counts":null,"_order_stock_reduced":null,"_new_order_email_sent":null,"_transaction_id":null,"_date_completed":null,"_completed_date":null,"_shipping_first_name":null,"_shipping_last_name":null,"_shipping_company":null,"_shipping_address_1":null,"_shipping_address_2":null,"_shipping_city":null,"_shipping_state":null,"_shipping_postcode":null,"_shipping_country":null,"Mercado Pago - Payment 19935461632":null,"Mercado Pago - Payment 20125334694":null,"Mercado Pago - Payment 20340802607":null,"Mercado Pago - Payment 20364723031":null,"_stripe_customer_id":null,"_stripe_source_id":null,"_stripe_intent_id":null,"_stripe_charge_captured":null,"_stripe_fee":null,"_stripe_net":null,"_stripe_currency":null,"_stripe_refund_id":null,"Mercado Pago - Payment 18279865598":null,"_refund_amount":null,"_refunded_by":null,"_refunded_payment":null,"_refund_reason":null,"_ux_tag":null,"_ux_page_template":null,"_booking_all_day":null,"_booking_cost":null,"_booking_customer_id":null,"_booking_order_item_id":null,"_booking_parent_id":null,"_booking_persons":null,"_booking_product_id":null,"_booking_resource_id":null,"_booking_start":null,"_booking_end":null,"_wc_bookings_gcalendar_event_id":null,"_wp_types_group_fields":null,"types_field_group_purpose":null,"_wp_types_group_post_types":null,"wpb_wctm_priority":null,"wpb_wctm_active_tab":null,"_wpb_rs_sync_id":null,"_wpb_rs_position":null,"_form":null,"_mail":null,"_mail_2":null,"_messages":null,"_additional_settings":null,"_locale":null,"_hash":null,"_edit_lock":"1782816840:471","_edit_last":"471","_wp_old_slug":null,"_wp_page_template":"page-blank.php","_footer":"normal","_yst_prominent_words_version":"1","_wpml_media_featured":"1","_wpml_media_duplicate":"1","_wpml_word_count":"{\"total\":419,\"to_translate\":{\"es\":35}}","_thumbnail_id":"7469","_wpml_media_has_media":"1","_wpml_location_migration_done":"1","_yoast_wpseo_content_score":"90","_yoast_wpseo_focuskeywords":"[]","_yoast_wpseo_keywordsynonyms":"[\"\"]","_last_translation_edit_mode":null,"_top_nav_excluded":null,"_cms_nav_minihome":null,"_yoast_wpseo_estimated-reading-time-minutes":"4","wp_schema_pro_optimized_structured_data":"<!-- Schema optimized by Schema Pro --><!-- \/ Schema optimized by Schema Pro --><!-- Schema optimized by Schema Pro --><script type=\"application\/ld+json\">[]<\/script><!-- \/ Schema optimized by Schema Pro --><!-- Schema optimized by Schema Pro --><script type=\"application\/ld+json\">[]<\/script><!-- \/ Schema optimized by Schema Pro -->","_trp_translated_slug_es_AR":"expediciones-aconcagua","_trp_translated_slug_pt_BR":null,"_yoast_wpseo_wordproof_timestamp":"","local-business-8472-name-fieldtype":"global-field","local-business-8472-name":"blogname","local-business-8472-schema-type-fieldtype":"global-field","local-business-8472-schema-type":"TravelAgency","local-business-8472-image-fieldtype":"global-field","local-business-8472-image":"featured_img","local-business-8472-telephone-fieldtype":"custom-field","local-business-8472-telephone":"+5492617159303","local-business-8472-price-range-fieldtype":"custom-field","local-business-8472-price-range":"$$","local-business-8472-url-fieldtype":"global-field","local-business-8472-url":"site_url","local-business-8472-location-street-fieldtype":"custom-field","local-business-8472-location-street":"Sobremonte 247","local-business-8472-location-locality-fieldtype":"custom-field","local-business-8472-location-locality":"Mendoza","local-business-8472-location-postal-fieldtype":"custom-field","local-business-8472-location-postal":"5502","local-business-8472-location-region-fieldtype":"custom-field","local-business-8472-location-region":"Mendoza","local-business-8472-location-country-fieldtype":"custom-field","local-business-8472-location-country":"AR","local-business-8472-hours-specification-fieldtype":"","local-business-8472-hours-specification":[{"days":"Monday,Tuesday,Wednesday,Thursday,Friday","days-fieldtype":"custom-field","days-custom":"Monday,Tuesday,Wednesday,Thursday,Friday","days-specific":"Monday,Tuesday,Wednesday,Thursday,Friday","opens":"09:00","opens-fieldtype":"custom-field","opens-custom":"09:00","opens-specific":"09:00","closes":"17:00","closes-fieldtype":"custom-field","closes-custom":"17:00","closes-specific":"17:00"}],"local-business-8472-geo-latitude-fieldtype":"custom-field","local-business-8472-geo-latitude":"","local-business-8472-geo-longitude-fieldtype":"custom-field","local-business-8472-geo-longitude":"","local-business-8472-rating-fieldtype":"custom-field","local-business-8472-rating":"","berocket_post_order":null,"_wp_trash_meta_status":null,"_wp_trash_meta_time":null,"_yoast_wpseo_title":"Discover Aconcagua Tours in Mendoza | SAK Wine & Travel","_yoast_wpseo_metadesc":"Join our Aconcagua Tours and explore the tallest peak in the Americas with expert guides and awe-inspiring views.","_yoast_wpseo_focuskw":"Aconcagua Tours","_yoast_wpseo_linkdex":"70","litespeed_vpi_list_mobile":["marca-sak_crema-1400x408.png"],"litespeed_vpi_list":["marca-sak_crema-1400x408.png","es_AR.png","Aconcagua-5.jpeg","plaza-franca-e1579722487616.jpg","plaza-francia2.jpg"],"_trp_automatically_translated_slug_es_AR":null,"_trp_automatically_translated_slug_pt_BR":"escalar-o-aconcagua","_wp_old_date":null,"footnotes":null,"total_sales":null,"_tax_status":null,"_tax_class":null,"_manage_stock":null,"_backorders":null,"_sold_individually":null,"_virtual":null,"_downloadable":null,"_download_limit":null,"_download_expiry":null,"_stock":null,"_stock_status":null,"_wc_average_rating":null,"_wc_review_count":null,"_product_version":null,"_number_of_dates":null,"_crosssell_ids":null,"_price":null,"_regular_price":null,"_wcml_custom_prices_status":null,"_wpb_rs_schema":null,"_order_currency":null,"_cart_discount":null,"_cart_discount_tax":null,"_order_shipping":null,"_order_shipping_tax":null,"_order_tax":null,"_order_total":null,"_order_version":null,"_prices_include_tax":null,"_links":{"self":[{"href":"https:\/\/sakwinetravel.com\/pt\/wp-json\/wp\/v2\/pages\/7741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sakwinetravel.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sakwinetravel.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sakwinetravel.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sakwinetravel.com\/pt\/wp-json\/wp\/v2\/comments?post=7741"}],"version-history":[{"count":2,"href":"https:\/\/sakwinetravel.com\/pt\/wp-json\/wp\/v2\/pages\/7741\/revisions"}],"predecessor-version":[{"id":12022,"href":"https:\/\/sakwinetravel.com\/pt\/wp-json\/wp\/v2\/pages\/7741\/revisions\/12022"}],"up":[{"embeddable":true,"href":"https:\/\/sakwinetravel.com\/pt\/wp-json\/wp\/v2\/pages\/6244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sakwinetravel.com\/pt\/wp-json\/wp\/v2\/media\/7469"}],"wp:attachment":[{"href":"https:\/\/sakwinetravel.com\/pt\/wp-json\/wp\/v2\/media?parent=7741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}